{"id":6452,"date":"2021-11-17T10:34:34","date_gmt":"2021-11-17T13:34:34","guid":{"rendered":"http:\/\/blog.cancaonova.com\/aracaju\/?p=6452"},"modified":"2021-11-17T13:51:21","modified_gmt":"2021-11-17T16:51:21","slug":"vem-ai-hosana-sergipe-2021","status":"publish","type":"post","link":"https:\/\/blog.cancaonova.com\/aracaju\/vem-ai-hosana-sergipe-2021\/","title":{"rendered":"Vem a\u00ed... Hosana Sergipe 2021"},"content":{"rendered":"<p>Um dos maiores eventos promovidos pela Comunidade Can\u00e7\u00e3o Nova em Aracaju est\u00e1 de volta!<\/p>\n<p><a href=\"http:\/\/blog.cancaonova.com\/aracaju\/vem-ai-hosana-sergipe-2021\/img_4094\/\" rel=\"attachment wp-att-6463\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-6463 alignleft\" src=\"http:\/\/blog.cancaonova.com\/aracaju\/files\/2021\/11\/IMG_4094-300x300.jpg\" alt=\"\" width=\"347\" height=\"347\" srcset=\"https:\/\/blog.cancaonova.com\/aracaju\/files\/2021\/11\/IMG_4094-300x300.jpg 300w, https:\/\/blog.cancaonova.com\/aracaju\/files\/2021\/11\/IMG_4094-150x150.jpg 150w, https:\/\/blog.cancaonova.com\/aracaju\/files\/2021\/11\/IMG_4094-144x144.jpg 144w\" sizes=\"(max-width: 347px) 100vw, 347px\" \/><\/a><\/p>\n<p>Desde 2009, o Hosana Sergipe \u00e9 realizado em Aracaju e neste ano de 2021 acontecer\u00e1 entre\u00a0os dias 10, 11 e 12 de dezembro de maneira presencial no Rinc\u00e3o do Meu Senhor na Can\u00e7\u00e3o Nova Aracaju.<\/p>\n<p>O evento \u00a0traz como tema: Coragem! Aquele que prometeu \u00e9 fiel. Sl 39, 7<\/p>\n<p>Diversos momentos com muita m\u00fasica, ora\u00e7\u00f5es e prega\u00e7\u00f5es.<\/p>\n<p>Presen\u00e7as confirmadas: Pitter Di Laura, Padre Adriano Zandon\u00e1, Di\u00e1cono Romulo Canuto, Sandro Arqueja e toda a Comunidade Can\u00e7\u00e3o Nova Aracaju.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Vendas das Pulseiras:<\/strong><\/p>\n<p>Loja Can\u00e7\u00e3o Nova Aracaju &#8211; Rua Paulo Henrique Machado Pimentel, 95.<\/p>\n<p><strong>Valores:<\/strong><\/p>\n<p>Combo (todos os dias) &#8211; R$ 20,00<\/p>\n<p>Sexta &#8211; livre<\/p>\n<p>S\u00e1bado &#8211; R$ 13,00 &#8211; Pulseira Azul<\/p>\n<p>Domingo &#8211; R$ 13,00 &#8211; Pulseira Amarela<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Locais de hospedagem com desconto:<\/strong><\/p>\n<p><b><span style=\"color: #0000ff\">Externato de S\u00e3o Francisco<\/span><\/b><\/p>\n<p>(79) 9148-5075 \u00a0\/ (79) 3224-3509<\/p>\n<p>Falar com a Irm\u00e3 Vera ou Rokyanna no hor\u00e1rio das 8h \u00e0s 11:30h ou das 13h \u00e0s 17h<\/p>\n<p><span style=\"color: #0000ff\"><b>Real Classic Hotel &#8211; ATALAIA &#8211;\u00a0<\/b><\/span>(79) 2106-7020<br \/>\nApresente a pulseira do evento e ganhe desconto.<\/p>\n<p><span style=\"color: #0000ff\"><b>Sandrin Praia Hotel &#8211; ATALAIA &#8211;\u00a0\u00a0(79) 3216-9600<\/b><\/span><br \/>\nApresente a pulseira do evento e ganhe desconto.<br \/>\n<em>Informa\u00e7\u00f5es Can\u00e7\u00e3o Nova &#8211;\u00a079 2104-4444<\/em><\/p>\n<p><em>Instagram: @cancanovaaracaju<\/em><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um dos maiores eventos promovidos pela Comunidade Can\u00e7\u00e3o Nova em Aracaju est\u00e1 de volta! Desde 2009, o Hosana Sergipe \u00e9 realizado em Aracaju e neste ano de 2021 acontecer\u00e1 entre\u00a0os dias 10, 11 e 12 de dezembro de maneira presencial&#8230;<\/p>\n","protected":false},"author":3351,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[4],"tags":[],"_links":{"self":[{"href":"https:\/\/blog.cancaonova.com\/aracaju\/wp-json\/wp\/v2\/posts\/6452"}],"collection":[{"href":"https:\/\/blog.cancaonova.com\/aracaju\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.cancaonova.com\/aracaju\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.cancaonova.com\/aracaju\/wp-json\/wp\/v2\/users\/3351"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.cancaonova.com\/aracaju\/wp-json\/wp\/v2\/comments?post=6452"}],"version-history":[{"count":4,"href":"https:\/\/blog.cancaonova.com\/aracaju\/wp-json\/wp\/v2\/posts\/6452\/revisions"}],"predecessor-version":[{"id":6467,"href":"https:\/\/blog.cancaonova.com\/aracaju\/wp-json\/wp\/v2\/posts\/6452\/revisions\/6467"}],"wp:attachment":[{"href":"https:\/\/blog.cancaonova.com\/aracaju\/wp-json\/wp\/v2\/media?parent=6452"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.cancaonova.com\/aracaju\/wp-json\/wp\/v2\/categories?post=6452"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.cancaonova.com\/aracaju\/wp-json\/wp\/v2\/tags?post=6452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}