{"id":7667,"date":"2009-02-26T23:33:11","date_gmt":"2009-02-26T20:33:11","guid":{"rendered":"http:\/\/blog.cancaonova.com\/felipeaquino\/?p=7667"},"modified":"2009-02-26T23:33:11","modified_gmt":"2009-02-26T20:33:11","slug":"o-que-o-povo-quer","status":"publish","type":"post","link":"https:\/\/blog.cancaonova.com\/felipeaquino\/2009\/02\/26\/o-que-o-povo-quer\/","title":{"rendered":"O QUE O POVO QUER"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: right\" align=\"right\"><span style=\"font-family: Times New Roman\"><span style=\"font-size: 13.5pt\">Padre Juliano Ribeiro Almeida<\/span><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: justify\"><span style=\"font-family: Times New Roman\"><span style=\"font-size: 13.5pt\">\u00a0<\/span><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: justify\"><span style=\"font-family: Times New Roman\"><span style=\"font-size: 13.5pt\"><span>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/span>A cena foi grotesca: o presidente Lula, do seu camarote na avenida Marqu\u00eas de Sapuca\u00ed, no Rio de Janeiro, lan\u00e7ando para o p\u00fablico camisinhas com a marca registrada do Minist\u00e9rio da Sa\u00fade. Nunca imaginei que chegaria a ver um presidente da Rep\u00fablica se prestando a t\u00e3o baixo papel. Lembrou-me a pol\u00edtica do \u201cpanis et circensis\u201d (p\u00e3o e circo), em que o imperador romano, do alto do seu camarote nos teatros p\u00fablicos da Roma antiga, mandava distribuir p\u00e3o gratuitamente para conter as massas. Al\u00e9m de j\u00e1 distribuir o p\u00e3o com seu programa Bolsa Fam\u00edlia, Lula agora decide avan\u00e7ar em seu vi\u00e9s de assistencialista, distribuindo orgasmo para o povo; afinal, como cantou a banda Tit\u00e3s, \u201ca gente n\u00e3o quer s\u00f3 comer; a gente quer comer e quer fazer amor. A gente n\u00e3o quer s\u00f3 comer, a gente quer prazer pra aliviar a dor\u201d. <\/span><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: justify\"><span style=\"font-size: 13.5pt\"><span style=\"font-family: Times New Roman\">\u00a0<\/span><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: justify\"><span style=\"font-family: Times New Roman\"><span style=\"font-size: 13.5pt\">E eu acrescentaria, para n\u00e3o faltar com a verdade: a gente n\u00e3o quer s\u00f3 prazer, a gente quer juros mais baixos e um bom sistema de sa\u00fade. O que a gente quer n\u00e3o \u00e9 t\u00e3o f\u00e1cil de distribuir e nem t\u00e3o descart\u00e1vel como um preservativo, numa aventura sexual de carnaval. A gente quer seguran\u00e7a p\u00fablica e qualidade de vida, a gente quer pol\u00edtica sem nepotismo, corporativismo e corrup\u00e7\u00e3o&#8230; Uma can\u00e7\u00e3o de Gilberto Gil diz: \u201co povo sabe o que quer, mas o povo tamb\u00e9m quer o que n\u00e3o sabe\u201d. Ainda quando n\u00e3o sabe nomear e definir bem, o povo quer valores morais, refer\u00eancias, ideais, cultura. <\/span><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: justify\"><span style=\"font-size: 13.5pt\"><span style=\"font-family: Times New Roman\">\u00a0<\/span><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: justify\"><span style=\"font-size: 13.5pt\"><span style=\"font-family: Times New Roman\">\u00c9 preciso deixar bem claro que os preservativos que Lula distribuiu no carnaval s\u00e3o paliativos, isto \u00e9, instrumentos que procuram conter momentaneamente o problema, mas n\u00e3o o resolvem, porque nem sequer tocam em suas causas. O governo est\u00e1 querendo conscientizar o povo em rela\u00e7\u00e3o \u00e0 camisinha. Mas \u00e9 preciso perguntar: o uso da camisinha conscientiza em rela\u00e7\u00e3o \u00e0 AIDS? Usar camisinha n\u00e3o significa eliminar o risco de ser contaminado, mas apenas cobrir o risco com uma camada fin\u00edssima de l\u00e1tex. Est\u00e1 provado que as DST\u2019s \u2013 doen\u00e7as sexualmente transmiss\u00edveis \u2013 se disseminam em situa\u00e7\u00f5es em que n\u00e3o h\u00e1 um comportamento sexual adequado. <\/span><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: justify\"><span style=\"font-size: 13.5pt\"><span style=\"font-family: Times New Roman\">\u00a0<\/span><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: justify\"><span style=\"font-family: Times New Roman\"><span style=\"font-size: 13.5pt\">Na pr\u00e1tica, isso quer dizer: onde h\u00e1 infidelidade conjugal, prostitui\u00e7\u00e3o, promiscuidade sexual, contato \u00edntimo sem respeito e compromisso. O que a sociedade est\u00e1 fazendo \u00e9 apenas ir aos lugares de risco, legitimar esse comportamento e distribuir camisinha num clima de \u201csalve-se quem puder\u201d. \u00c9 como se um navio n\u00e3o desse a m\u00ednima para as normas de seguran\u00e7a na navega\u00e7\u00e3o e se limitasse a distribuir coletes salva-vidas quando o navio amea\u00e7asse afundar.<\/span><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: justify\"><span style=\"font-size: 13.5pt\"><span style=\"font-family: Times New Roman\">\u00a0<\/span><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: justify\"><span style=\"font-family: Times New Roman\"><span style=\"font-size: 13.5pt\">O problema das DST\u2019s precisa ser enfrentado, claro. \u00c9 preciso haver programas de informa\u00e7\u00e3o, preven\u00e7\u00e3o e, por fim, interven\u00e7\u00e3o tamb\u00e9m com a\u00e7\u00f5es paliativas para os que n\u00e3o foram convencidos a mudar de comportamento. Sem d\u00favida. Mas a preocupa\u00e7\u00e3o do governo em conter o HIV n\u00e3o pode ser apenas a de diminuir os gastos do SUS com o tratamento dos soropositivos. Sua preocupa\u00e7\u00e3o deve estar com o bem-estar integral da pessoa, sua harmonia familiar, seu correto desenvolvimento sexual. E \u00e9 simplesmente imposs\u00edvel tratar de todas essas quest\u00f5es apenas distribuindo camisinha, sem sugerir claramente: repense sua vida sexual, pergunte-se se j\u00e1 \u00e9 o momento adequado para transar, ou\u00e7a sua fam\u00edlia e sua religi\u00e3o, escolha bem a pessoa a quem voc\u00ea pretende entregar o seu corpo. <\/span><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: justify\"><span style=\"font-size: 13.5pt\"><span style=\"font-family: Times New Roman\">\u00a0<\/span><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: justify\"><span style=\"font-family: Times New Roman\"><span style=\"font-size: 13.5pt\">Tenho certeza que Lula e dona Marisa n\u00e3o teriam coragem de jogar camisinhas do camarote se tivessem uma filha de 13 anos l\u00e1 embaixo, na quentura da puberdade e no embalo do carnaval. <\/span><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: justify\"><span style=\"font-size: small\"><span style=\"font-family: Times New Roman\">\u00a0<\/span><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt;text-align: justify\"><span style=\"font-size: 13.5pt\"><span style=\"font-family: Times New Roman\">Juliano Ribeiro Almeida, 28 anos,\u00a0\u00e9 padre cat\u00f3lico e trabalha em Cachoeiro de Itapemirim. <\/span><a href=\"mai&#108;&#116;&#x6f;&#x3a;&#x6a;&#x75;&#x6c;ian&#111;&#114;&#x69;&#x61;&#x6c;&#x40;&#x67;mai&#108;&#46;&#x63;&#x6f;&#x6d;\"><span style=\"font-family: Times New Roman\">&#x6a;&#x75;&#x6c;&#x69;&#97;&#110;ori&#x61;&#x6c;&#x40;&#x67;&#x6d;&#97;&#105;l.c&#x6f;&#x6d;<\/span><\/a><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt\"><span style=\"font-size: small;font-family: Times New Roman\">\u00a0<\/span><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Padre Juliano Ribeiro Almeida \u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 A cena foi grotesca: o presidente Lula, do seu camarote na avenida Marqu\u00eas de Sapuca\u00ed, no Rio de Janeiro, lan\u00e7ando para o p\u00fablico camisinhas com a marca registrada do Minist\u00e9rio da Sa\u00fade. Nunca imaginei&#8230;<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":29,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[771],"tags":[],"_links":{"self":[{"href":"https:\/\/blog.cancaonova.com\/felipeaquino\/wp-json\/wp\/v2\/posts\/7667"}],"collection":[{"href":"https:\/\/blog.cancaonova.com\/felipeaquino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.cancaonova.com\/felipeaquino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.cancaonova.com\/felipeaquino\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.cancaonova.com\/felipeaquino\/wp-json\/wp\/v2\/comments?post=7667"}],"version-history":[{"count":1,"href":"https:\/\/blog.cancaonova.com\/felipeaquino\/wp-json\/wp\/v2\/posts\/7667\/revisions"}],"predecessor-version":[{"id":7668,"href":"https:\/\/blog.cancaonova.com\/felipeaquino\/wp-json\/wp\/v2\/posts\/7667\/revisions\/7668"}],"wp:attachment":[{"href":"https:\/\/blog.cancaonova.com\/felipeaquino\/wp-json\/wp\/v2\/media?parent=7667"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.cancaonova.com\/felipeaquino\/wp-json\/wp\/v2\/categories?post=7667"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.cancaonova.com\/felipeaquino\/wp-json\/wp\/v2\/tags?post=7667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}