{"id":11694,"date":"2015-03-23T15:31:49","date_gmt":"2015-03-23T18:31:49","guid":{"rendered":"http:\/\/blog.cancaonova.com\/natal\/2015\/03\/23\/a-origem-da-quaresma\/"},"modified":"2015-03-23T15:31:49","modified_gmt":"2015-03-23T18:31:49","slug":"a-origem-da-quaresma","status":"publish","type":"post","link":"https:\/\/blog.cancaonova.com\/natal\/2015\/03\/23\/a-origem-da-quaresma\/","title":{"rendered":"A origem da Quaresma"},"content":{"rendered":"<p><del><\/del><\/p>\n<p><strong>A Quaresma foi inspirada numa grande catequese que a Igreja primitiva realizava<\/strong><\/p>\n<p>Dentre todas as solenidades crist\u00e3s, o primeiro lugar \u00e9 ocupado pelo mist\u00e9rio pascal, porque devemos nos preparar para viv\u00ea-lo convenientemente. Por isso, foi institu\u00edda a Quaresma, um tempo de quarenta dias para chegarmos dignamente \u00e0 celebra\u00e7\u00e3o do Tr\u00edduo Pascal.<\/p>\n<p><a href=\"http:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/6\/2015\/03\/formacao_a-origem-da-quaresma-.jpg\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-76982\" src=\"http:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/6\/2015\/03\/formacao_a-origem-da-quaresma-.jpg\" alt=\"A origem da quaresma\" width=\"940\" height=\"500\" \/><\/a><\/p>\n<p>A Quaresma, como pr\u00e1tica obrigat\u00f3ria, foi institu\u00edda no s\u00e9culo IV, mas,<strong> desde sempre, os crist\u00e3os se preparavam para a P\u00e1scoa com ora\u00e7\u00e3o intensa, jejum e penit\u00eancia.<\/strong> O n\u00famero de quarenta dias tem um significado simb\u00f3lico-b\u00edblico: quarenta s\u00e3o os dias do dil\u00favio, da perman\u00eancia de Mois\u00e9s no Monte Sinai, das tenta\u00e7\u00f5es de Jesus. Guiados por esse tempo e pelas pr\u00e1ticas\u00a0\u2013\u00a0como que guiados por uma b\u00fassola \u2013, buscamos os tesouros da f\u00e9 para crescer no seguimento de Nosso Senhor Jesus Cristo.<\/p>\n<p><em>\u201cAgora, diz o Senhor, voltai para mim com todo o vosso cora\u00e7\u00e3o, com jejuns, l\u00e1grimas e gemidos; rasgai o cora\u00e7\u00e3o e n\u00e3o as vestes; e voltai para o Senhor, vosso Deus; ele \u00e9 benigno e compassivo, paciente e cheio de miseric\u00f3rdia, inclinado a perdoar o castigo\u201d (Cf. Joel 12, 12-13).<\/em><\/p>\n<p>Este tempo de quarenta dias foi inspirado numa grande catequese que a Igreja primitiva realizava. Ela durava quarenta dias, tempo em que os pag\u00e3os (catec\u00famenos) se preparavam para receber o batismo no S\u00e1bado Santo, dentro da Solenidade da Vig\u00edlia Pascal. Acompanhavam tamb\u00e9m os irm\u00e3os que tinham cometido pecados graves para retornarem \u00e0 f\u00e9. Esse tempo era marcado pela penit\u00eancia e ora\u00e7\u00e3o, pelo jejum e pela escuta da Palavra de Deus. Eles eram os \u201cpenitentes\u201d, os quais renovavam a f\u00e9 e recebiam o batismo ou eram reintegrados \u00e0 comunidade no S\u00e1bado Santo.<\/p>\n<p>Na Quarta-feira de Cinzas, iniciamos o tempo mais rico e profundo da liturgia. Na verdade, esse tempo, que abrange a Quaresma, Semana Santa e P\u00e1scoa at\u00e9 Pentecostes, \u00e9 um grande retiro, centro do Mist\u00e9rio de Cristo e da nossa f\u00e9 e salva\u00e7\u00e3o. Tempo privilegiado de convers\u00e3o e combate espiritual, de jejum medicinal e caritativo. A Quaresma ainda \u00e9, sobretudo, tempo de escuta da Palavra de Deus, de uma catequese mais profunda, que recorda aos crist\u00e3os os grandes temas batismais em prepara\u00e7\u00e3o para a P\u00e1scoa.<\/p>\n<p>Toda a nossa vida se torna um sacrif\u00edcio espiritual, que apresentamos continuamente ao Pai em uni\u00e3o com o sacrif\u00edcio de Jesus sofredor e pobre, a fim de que, por Ele, com Ele e n\u2019Ele, seja o Pai em tudo louvado e glorificado. Por isso, a Quaresma \u00e9 um caminho b\u00edblico, pastoral, lit\u00fargico e existencial para cada crist\u00e3o pessoalmente e para a comunidade crist\u00e3 em geral, que come\u00e7a com as cinzas e termina com a noite da luz e do fogo, a noite santa da P\u00e1scoa da Ressurrei\u00e7\u00e3o de Nosso Senhor Jesus Cristo.<\/p>\n<p>Vamos refletir sobre os rumos de nossa espiritualidade at\u00e9 a P\u00e1scoa de Nosso Senhor Jesus, ou seja, a vida nova que o Ele tem para n\u00f3s, os exerc\u00edcios quaresmais de convers\u00e3o. A liturgia da Quarta-feira de Cinzas manda proclamar o Evangelho em que Nosso Senhor fala da esmola, da ora\u00e7\u00e3o e do jejum, conforme Mateus 6,1-8. 16-18.<\/p>\n<div id=\"attachment_11695\" style=\"width: 160px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/blog.cancaonova.com\/natal\/files\/2015\/03\/113_thumb.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-11695\" class=\"wp-image-11695 size-thumbnail\" src=\"http:\/\/blog.cancaonova.com\/natal\/files\/2015\/03\/113_thumb-150x150.jpg\" alt=\"113_thumb\" width=\"150\" height=\"150\" \/><\/a><p id=\"caption-attachment-11695\" class=\"wp-caption-text\">Padre Luizinho, natural de Feira de Santana (BA), \u00e9 sacerdote na Comunidade Can\u00e7\u00e3o Nova. Ordenado em 22 de dezembro de 2000, cujo lema sacerdotal \u00e9 \u201cTudo posso naquele que me d\u00e1 for\u00e7a\u201d.<\/p><\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Quaresma foi inspirada numa grande catequese que a Igreja primitiva realizava Dentre todas as solenidades crist\u00e3s, o primeiro lugar \u00e9 ocupado pelo mist\u00e9rio pascal, porque devemos nos preparar para viv\u00ea-lo convenientemente. Por isso, foi institu\u00edda a Quaresma, um tempo&#8230;<\/p>\n","protected":false},"author":3131,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[23,15731],"tags":[],"_links":{"self":[{"href":"https:\/\/blog.cancaonova.com\/natal\/wp-json\/wp\/v2\/posts\/11694"}],"collection":[{"href":"https:\/\/blog.cancaonova.com\/natal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.cancaonova.com\/natal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.cancaonova.com\/natal\/wp-json\/wp\/v2\/users\/3131"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.cancaonova.com\/natal\/wp-json\/wp\/v2\/comments?post=11694"}],"version-history":[{"count":1,"href":"https:\/\/blog.cancaonova.com\/natal\/wp-json\/wp\/v2\/posts\/11694\/revisions"}],"predecessor-version":[{"id":11696,"href":"https:\/\/blog.cancaonova.com\/natal\/wp-json\/wp\/v2\/posts\/11694\/revisions\/11696"}],"wp:attachment":[{"href":"https:\/\/blog.cancaonova.com\/natal\/wp-json\/wp\/v2\/media?parent=11694"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.cancaonova.com\/natal\/wp-json\/wp\/v2\/categories?post=11694"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.cancaonova.com\/natal\/wp-json\/wp\/v2\/tags?post=11694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}