{"id":11709,"date":"2015-03-24T10:56:23","date_gmt":"2015-03-24T13:56:23","guid":{"rendered":"http:\/\/blog.cancaonova.com\/natal\/2015\/03\/24\/o-perdao-como-libera-lo\/"},"modified":"2015-03-24T10:56:23","modified_gmt":"2015-03-24T13:56:23","slug":"o-perdao-como-libera-lo","status":"publish","type":"post","link":"https:\/\/blog.cancaonova.com\/natal\/2015\/03\/24\/o-perdao-como-libera-lo\/","title":{"rendered":"O perd\u00e3o, como libera-lo?"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/blog.cancaonova.com\/natal\/files\/2015\/03\/images.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-11710\" src=\"http:\/\/blog.cancaonova.com\/natal\/files\/2015\/03\/images.png\" alt=\"images\" width=\"300\" height=\"401\" srcset=\"https:\/\/blog.cancaonova.com\/natal\/files\/2015\/03\/images.png 194w, https:\/\/blog.cancaonova.com\/natal\/files\/2015\/03\/images-150x200.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>O perd\u00e3o come\u00e7a sempre em nosso cora\u00e7\u00e3o. Passa depois pela nossa intelig\u00eancia. \u00c9 uma decis\u00e3o! Depois de concebido no cora\u00e7\u00e3o e gestado no pensamento, ele [perd\u00e3o] ganha vida por uma decis\u00e3o irrevers\u00edvel e expl\u00edcita. Enquanto n\u00e3o perdoamos, perpetuamos a falsa ideia de que a vingan\u00e7a e o \u00f3dio podem ser rem\u00e9dios para curar nossa dor, a vingan\u00e7a parece ser mais justa do que o perd\u00e3o. Mas \u00e9 s\u00f3 na hora. A longo prazo suas consequ\u00eancias ser\u00e3o terr\u00edveis e cru\u00e9is.<\/p>\n<p>O perd\u00e3o afeta o presente e o futuro, mas n\u00e3o pode mexer no passado. N\u00e3o adianta nada querer sonhar com o passado melhor ou diferente. O passado foi o que foi. N\u00e3o h\u00e1 o que fazer para mud\u00e1-lo. Podemos e devemos assimil\u00e1-lo e aprender o que ele tem a nos ensinar. Mais do que isso \u00e9 imposs\u00edvel.<strong><br \/>\n<\/strong><br \/>\nA esperan\u00e7a por um passado melhor \u00e9 uma ilus\u00e3o do encardido [dem\u00f4nio]. Ele \u00e9 o grande especialista em passado.\u00a0<strong>Jesus, ao contr\u00e1rio, nunca fez nenhuma pergunta sobre o passado de nenhuma pessoa.<\/strong>\u00a0Ele nunca fez uma regress\u00e3o ao passado com ningu\u00e9m. Nem mesmo com aqueles que tinham s\u00e9rios problemas afetivos e at\u00e9 sexuais. Parece estranho que o Senhor n\u00e3o tenha realizado uma sess\u00e3o de cura interior das etapas cronol\u00f3gicas com Maria Madalena, Maria de Bet\u00e2nia, a Samaritana, Zaqueu, Pedro, Tiago e Jo\u00e3o, Judas e tantos outros que, por suas atitudes, demonstraram carregar s\u00e9rios problemas oriundos da inf\u00e2ncia e mesmo na gesta\u00e7\u00e3o.<\/p>\n<p>Cristo n\u00e3o retomava o passado porque sabia que a \u00fanica coisa que podemos fazer em rela\u00e7\u00e3o ao passado \u00e9 enxerg\u00e1-lo de um jeito novo e aprender com o que ele tem a nos ensinar. Mas isso se faz vivendo intensamente o presente e projetando o futuro. Jesus foi o grande mestre do perd\u00e3o. Ele nos mostra que o perd\u00e3o n\u00e3o acontece de uma hora para outra e nem pode ser uma tentativa de abafar ou simplesmente ignorar essa dor. O perd\u00e3o \u00e9 um processo profundo, repetido tantas vezes quantas forem necess\u00e1rias no nosso \u00edntimo. A pressa \u00e9 inimiga do perd\u00e3o!<\/p>\n<p>O perd\u00e3o nos ensina a nos relacionar, de modo maduro, com o passado. N\u00e3o \u00e9 um puro esquecimento dos fatos, nem sua condena\u00e7\u00e3o. N\u00e3o \u00e9 a coloca\u00e7\u00e3o de panos quentes e muito menos a tentativa de amenizar os acontecimentos. Perdoar \u00e9 ser realista o suficiente para come\u00e7ar a ver o passado com os olhos do presente, voltados para o futuro.<\/p>\n<p><strong>Quem n\u00e3o perdoa n\u00e3o consegue se libertar das garras, interiores e exteriores, daquele que o machucou<\/strong>. Mesmo que seja necess\u00e1rio se afastar, tempor\u00e1ria ou definitivamente, dessa pessoa, s\u00f3 podemos faz\u00ea-lo num clima de perd\u00e3o.<\/p>\n<p>Antes de colocar para fora do nosso cora\u00e7\u00e3o algu\u00e9m que nos machucou \u00e9 preciso perdo\u00e1-lo. Sem perd\u00e3o, essa pessoa vai permanecer ocupando um espa\u00e7o precioso de nossa vida e continuar\u00e1 tendo um poder terr\u00edvel sobre n\u00f3s.<\/p>\n<p><em>Do livro \u201cGotas de cura interior\u201d.<\/em><\/p>\n<p><iframe loading=\"lazy\" title=\"EXERCICIOS PRATICOS PARA A CURA DO RESSENTIMENTO - PADRE LEO\" width=\"600\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/XAajtYPn7Ow?feature=oembed&amp;rel=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; O perd\u00e3o come\u00e7a sempre em nosso cora\u00e7\u00e3o. Passa depois pela nossa intelig\u00eancia. \u00c9 uma decis\u00e3o! Depois de concebido no cora\u00e7\u00e3o e gestado no pensamento, ele [perd\u00e3o] ganha vida por uma decis\u00e3o irrevers\u00edvel e expl\u00edcita. Enquanto n\u00e3o perdoamos, perpetuamos a&#8230;<\/p>\n","protected":false},"author":3131,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[12581,23,15731],"tags":[],"_links":{"self":[{"href":"https:\/\/blog.cancaonova.com\/natal\/wp-json\/wp\/v2\/posts\/11709"}],"collection":[{"href":"https:\/\/blog.cancaonova.com\/natal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.cancaonova.com\/natal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.cancaonova.com\/natal\/wp-json\/wp\/v2\/users\/3131"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.cancaonova.com\/natal\/wp-json\/wp\/v2\/comments?post=11709"}],"version-history":[{"count":1,"href":"https:\/\/blog.cancaonova.com\/natal\/wp-json\/wp\/v2\/posts\/11709\/revisions"}],"predecessor-version":[{"id":11711,"href":"https:\/\/blog.cancaonova.com\/natal\/wp-json\/wp\/v2\/posts\/11709\/revisions\/11711"}],"wp:attachment":[{"href":"https:\/\/blog.cancaonova.com\/natal\/wp-json\/wp\/v2\/media?parent=11709"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.cancaonova.com\/natal\/wp-json\/wp\/v2\/categories?post=11709"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.cancaonova.com\/natal\/wp-json\/wp\/v2\/tags?post=11709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}