{"id":11838,"date":"2015-05-11T09:41:10","date_gmt":"2015-05-11T12:41:10","guid":{"rendered":"http:\/\/blog.cancaonova.com\/natal\/?p=11838"},"modified":"2015-05-11T09:41:10","modified_gmt":"2015-05-11T12:41:10","slug":"uma-vida-plena-em-jesus-e-feita-de-renuncias-diarias","status":"publish","type":"post","link":"https:\/\/blog.cancaonova.com\/natal\/2015\/05\/11\/uma-vida-plena-em-jesus-e-feita-de-renuncias-diarias\/","title":{"rendered":"Uma vida plena em Jesus \u00e9 feita de ren\u00fancias di\u00e1rias"},"content":{"rendered":"<div class=\"socialmedia-top\"><\/div>\n<p><strong>Quando n\u00f3s sabemos renunciar \u00e0 nossa vontade e abra\u00e7amos a nossa cruz de cada dia, a nossa vida passa a ter um outro sentido!<\/strong><\/p>\n<p><em>\u201dSe algu\u00e9m me quer seguir, renuncie a si mesmo, tome sua cruz cada dia, e siga-me\u201d\u00a0<\/em>(Lc 9,23).<img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-11840\" src=\"http:\/\/blog.cancaonova.com\/natal\/files\/2015\/05\/jesus-224x280.jpg\" alt=\"jesus\" width=\"335\" height=\"419\" srcset=\"https:\/\/blog.cancaonova.com\/natal\/files\/2015\/05\/jesus-224x280.jpg 224w, https:\/\/blog.cancaonova.com\/natal\/files\/2015\/05\/jesus.jpg 600w\" sizes=\"(max-width: 335px) 100vw, 335px\" \/><\/p>\n<p>Seguir Jesus significa ir atr\u00e1s dos Seus passos, fazer aquilo que Ele fez. Seguir Jesus n\u00e3o \u00e9 simplesmente imit\u00e1-Lo, copi\u00e1-Lo, mas \u00e9 ir na mesma dire\u00e7\u00e3o, no caminho da vida, no sentido da vida. E por isso que o Senhor n\u00e3o s\u00f3 ensina o caminho, mas Ele mesmo faz e \u00e9 o caminho, Ele mesmo desce ao nosso meio e se faz um de n\u00f3s e caminha para o c\u00e9u, nos chamando para irmos atr\u00e1s d\u2019Ele.<\/p>\n<p>Para irmos atr\u00e1s do Senhor, antes de passarmos pela porta do c\u00e9u, precisaremos passar por \u201cJerusal\u00e9m\u201d como o Senhor mesmo fez. Ali o Senhor viveu a vida no meio de n\u00f3s, primeiro renunciando a si mesmo: renunciou a Sua condi\u00e7\u00e3o divina, renunciou aos t\u00edtulos, \u00e0s honrarias humanas para viver o projeto do Reino de Deus. E\u00a0tomou a Sua cruz, a cruz da rejei\u00e7\u00e3o, a cruz do peso dos nossos pecados, a cruz da n\u00e3o aceita\u00e7\u00e3o e se entregou inteiramente ao Pai.<\/p>\n<p>Quem quiser segui-Lo precisa tomar a mesma atitude: renunciar a si mesmo.<!--more continue lendo--> Sim, ser capaz de renunciar ao pr\u00f3prio \u201ceu\u201d, muitas vezes, aos afetos, ao desejo de agradar e viver a vida conforme o projeto de Deus para n\u00f3s.<\/p>\n<p><strong>Como \u00e9 dif\u00edcil renunciar a n\u00f3s mesmos, porque somos t\u00e3o orgulhosos, ego\u00edstas, queremos ver o mundo do nosso jeito, da nossa maneira!<\/strong>\u00a0Quando sabemos ceder, quando, mesmo nos achando certos, somos capazes de abaixar a nossa cabe\u00e7a, conseguimos viver ren\u00fancias em nossa vida. Ren\u00fancia \u00e0 vontade de ter isso ou aquilo, renuncia a afetos que gostar\u00edamos de viver com mais intensidade e n\u00e3o \u00e9 poss\u00edvel os viver. Tudo isso devemos fazer como obla\u00e7\u00e3o, como entrega, como oferta a Deus.<\/p>\n<p>Quando n\u00f3s, ent\u00e3o fazemos isso tudo, n\u00f3s pegamos a nossa cruz e vamos atr\u00e1s de Jesus, mas essa cruz \u00e9 a mais pesada: a cruz dos nossos dramas pessoais, familiares, a cruz da doen\u00e7a, da enfermidade, dos pequenos sofrimentos, dos aborrecimentos que vivemos em nossa vida, em nosso corpo, em nossa mente. Vivemos tudo isso em um esp\u00edrito de entrega e obla\u00e7\u00e3o a Deus quando n\u00f3s sabemos renunciar \u00e0 nossa vontade e abra\u00e7amos a nossa cruz de cada dia; dessa forma a nossa vida passa a ter um outro sentido! N\u00e3o \u00e9 que deixamos de viver, ao contr\u00e1rio, a nossa vida se torna mais plena, ela passa ter um sentido de eternidade, ela passa a caminhar na dire\u00e7\u00e3o do c\u00e9u.<\/p>\n<p>Que n\u00f3s possamos, em vez de imaginar que estamos perdendo a vida, tomar consci\u00eancia de que seguir Jesus \u00e9 perder a vida neste mundo para ganh\u00e1-la aqui e para sempre com um sentido mais pleno.<\/p>\n<p>Deus aben\u00e7oe voc\u00ea!<\/p>\n<p>&nbsp;<\/p>\n<footer id=\"entry-author-info\"><a class=\"entry_author_image\" href=\"http:\/\/homilia.cancaonova.com\/author\/homilia\/\"><img decoding=\"async\" src=\"http:\/\/img.cancaonova.com\/cnimages\/canais\/authors\/3_thumb.jpg\" alt=\"\" \/><\/a><\/p>\n<h2>Padre Roger Ara\u00fajo<\/h2>\n<p>Sacerdote da Comunidade Can\u00e7\u00e3o Nova, jornalista e colaborador do Portal Can\u00e7\u00e3o Nova.<\/p>\n<p><a href=\"https:\/\/www.facebook.com\/rogeraraujo.cn\" target=\"_blank\" rel=\"nofollow\">https:\/\/www.facebook.com\/rogeraraujo.cn<\/a><\/p>\n<\/footer>\n<footer><\/footer>\n","protected":false},"excerpt":{"rendered":"<p>Quando n\u00f3s sabemos renunciar \u00e0 nossa vontade e abra\u00e7amos a nossa cruz de cada dia, a nossa vida passa a ter um outro sentido! \u201dSe algu\u00e9m me quer seguir, renuncie a si mesmo, tome sua cruz cada dia, e siga-me\u201d\u00a0(Lc&#8230;<\/p>\n","protected":false},"author":3131,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[15731],"tags":[],"_links":{"self":[{"href":"https:\/\/blog.cancaonova.com\/natal\/wp-json\/wp\/v2\/posts\/11838"}],"collection":[{"href":"https:\/\/blog.cancaonova.com\/natal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.cancaonova.com\/natal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.cancaonova.com\/natal\/wp-json\/wp\/v2\/users\/3131"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.cancaonova.com\/natal\/wp-json\/wp\/v2\/comments?post=11838"}],"version-history":[{"count":2,"href":"https:\/\/blog.cancaonova.com\/natal\/wp-json\/wp\/v2\/posts\/11838\/revisions"}],"predecessor-version":[{"id":11841,"href":"https:\/\/blog.cancaonova.com\/natal\/wp-json\/wp\/v2\/posts\/11838\/revisions\/11841"}],"wp:attachment":[{"href":"https:\/\/blog.cancaonova.com\/natal\/wp-json\/wp\/v2\/media?parent=11838"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.cancaonova.com\/natal\/wp-json\/wp\/v2\/categories?post=11838"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.cancaonova.com\/natal\/wp-json\/wp\/v2\/tags?post=11838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}