{"id":10567,"date":"2021-10-11T00:00:39","date_gmt":"2021-10-11T02:00:39","guid":{"rendered":"http:\/\/blog.cancaonova.com\/paisecatequistas\/?p=10567"},"modified":"2024-10-02T16:58:29","modified_gmt":"2024-10-02T18:58:29","slug":"da-pra-ser-jovem-e-ser-santo-nos-tempos-de-hoje","status":"publish","type":"post","link":"https:\/\/blog.cancaonova.com\/paisecatequistas\/da-pra-ser-jovem-e-ser-santo-nos-tempos-de-hoje\/","title":{"rendered":"Carlo Acutis e o caminho para o C\u00e9u"},"content":{"rendered":"<h4>D\u00e1 para ser jovem e ser santo nos tempos de hoje? Sim, d\u00e1 sim!<\/h4>\n<p>D\u00e1 para ser jovem, jogar videogame, jogar bola, usar a internet com responsabilidade e equil\u00edbrio, usar cal\u00e7a jeans e ainda ser santo!<\/p>\n<p>Carlo , foi um adolescente italiano que buscou a santidade nas coisas simples, vivendo como a Igreja ensina. Ele nasceu em 1991, e morreu em 2006, aos 15 anos. Foi beatificado em outubro de 2020.<\/p>\n<p><strong>&#8220;Beato&#8221;<\/strong> \u00e9 o t\u00edtulo que vem antes de <strong>&#8220;Santo&#8221;<\/strong>.<\/p>\n<p>Ele gostava muito de computadores e aprendeu a programar sites. Chegou a fazer um com hist\u00f3rias de santos e milagres eucar\u00edsticos para as pessoas conhecerem mais sobre a riqueza da vida em Deus.<\/p>\n<p>Andava de bicicleta para cima e para baixo, sempre com seu ter\u00e7o enrolado no pulso.<\/p>\n<p>Gostava muito de ajudar os moradores de rua, e fazia amizade com facilidade, porque sentia que o Senhor n\u00e3o ficaria feliz se eles fizessem algo violento, mesmo contra algu\u00e9m que os tratasse mal.<\/p>\n<p>Carlo descobriu o amor de Jesus na Eucaristia muito pequeno, e fez sua primeira comunh\u00e3o aos sete anos de idade. No seu site, ele contava os segredos que usava para ser bom:<\/p>\n<ul>\n<li>Ir a missa todos os dias,<\/li>\n<li>Rezar o ter\u00e7o todos os dias,<\/li>\n<li>Confessar-se sempre que for preciso;<\/li>\n<li>Ler a B\u00edblia e pedir muita ajuda dos Santos e do seu Anjo da Guarda.<\/li>\n<\/ul>\n<p>Era muito devoto de S\u00e3o Francisco Marto (um dos pastorinhos que estavam nas apari\u00e7\u00f5es em F\u00e1tima, por isso rezava o santo ter\u00e7o todos os dias.<\/p>\n<p>Carlo morreu de leucemia (c\u00e2ncer no sangue), mas, antes de morrer, disse aos seus pais:<em> &#8220;Eu ofere\u00e7o meu sofrimento pela Igreja e pelo Papa, para que eu n\u00e3o precise ir para o purgat\u00f3rio e v\u00e1 direto para o C\u00e9u, e pela convers\u00e3o dos pecadores&#8221;.<\/em><\/p>\n<p>Se pensarmos bem, n\u00e3o h\u00e1 nada de mirabolante ou extraordin\u00e1rio na vida de Carlo Acutis.<\/p>\n<p>Assim como muitos santos, ele apenas buscou viver a fidelidade a Jesus e \u00e0 Igreja Cat\u00f3lica.<\/p>\n<p>Quando Deus nos pede a santidade, Ele sabe que n\u00f3s somos capazes de ser santo!<\/p>\n<ul>\n<li><a href=\"https:\/\/blog.cancaonova.com\/paisecatequistas\/2021\/10\/11\/todos-nos-podemos-ser-santos-carlos-acutis\/\"><strong>Todos n\u00f3s podemos ser santos!<\/strong><\/a><\/li>\n<\/ul>\n<p>Vamos assistir a este epis\u00f3dio do Cantinho da Crian\u00e7a e ver como \u00e9 poss\u00edvel ser santo!<\/p>\n<p><iframe loading=\"lazy\" title=\"Programa Cantinho da Crian\u00c3\u00a7a -  Ser Santo\" width=\"600\" height=\"338\" src=\"https:\/\/www.youtube.com\/embed\/zFv5qKiva6M?feature=oembed&amp;rel=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>E a\u00ed, vamos entrar nesse caminho de santidade agora?<\/p>\n<p><a href=\"https:\/\/blog.cancaonova.com\/paisecatequistas\/files\/2021\/10\/carlo.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-17978 alignnone\" src=\"https:\/\/blog.cancaonova.com\/paisecatequistas\/files\/2021\/10\/carlo.jpg\" alt=\"\" width=\"1414\" height=\"2000\" srcset=\"https:\/\/blog.cancaonova.com\/paisecatequistas\/files\/2021\/10\/carlo.jpg 1414w, https:\/\/blog.cancaonova.com\/paisecatequistas\/files\/2021\/10\/carlo-212x300.jpg 212w, https:\/\/blog.cancaonova.com\/paisecatequistas\/files\/2021\/10\/carlo-768x1086.jpg 768w, https:\/\/blog.cancaonova.com\/paisecatequistas\/files\/2021\/10\/carlo-1086x1536.jpg 1086w\" sizes=\"(max-width: 1414px) 100vw, 1414px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: right\">\n","protected":false},"excerpt":{"rendered":"<p>Se a gente pensar bem, n\u00e3o tem nada de mirabolante ou extraordin\u00e1rio na vida de Carlo Acutis.\u00a0D\u00e1 pra ser jovem, jogar v\u00eddeo game, jogar bola, usar a internet com responsabilidade e equil\u00edbrio, usar cal\u00e7a jeans ainda ser santo! <a href=\"https:\/\/blog.cancaonova.com\/paisecatequistas\/da-pra-ser-jovem-e-ser-santo-nos-tempos-de-hoje\/\">Continue lendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":4414,"featured_media":17972,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[23,271],"tags":[9421,19623,200775,16148,16595,15521,203638,17108,8001,3671,3211,29584,7931,17268,24722,201042],"_links":{"self":[{"href":"https:\/\/blog.cancaonova.com\/paisecatequistas\/wp-json\/wp\/v2\/posts\/10567"}],"collection":[{"href":"https:\/\/blog.cancaonova.com\/paisecatequistas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.cancaonova.com\/paisecatequistas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.cancaonova.com\/paisecatequistas\/wp-json\/wp\/v2\/users\/4414"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.cancaonova.com\/paisecatequistas\/wp-json\/wp\/v2\/comments?post=10567"}],"version-history":[{"count":17,"href":"https:\/\/blog.cancaonova.com\/paisecatequistas\/wp-json\/wp\/v2\/posts\/10567\/revisions"}],"predecessor-version":[{"id":17982,"href":"https:\/\/blog.cancaonova.com\/paisecatequistas\/wp-json\/wp\/v2\/posts\/10567\/revisions\/17982"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.cancaonova.com\/paisecatequistas\/wp-json\/wp\/v2\/media\/17972"}],"wp:attachment":[{"href":"https:\/\/blog.cancaonova.com\/paisecatequistas\/wp-json\/wp\/v2\/media?parent=10567"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.cancaonova.com\/paisecatequistas\/wp-json\/wp\/v2\/categories?post=10567"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.cancaonova.com\/paisecatequistas\/wp-json\/wp\/v2\/tags?post=10567"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}