{"id":12163,"date":"2021-07-17T00:00:38","date_gmt":"2021-07-17T02:00:38","guid":{"rendered":"http:\/\/blog.cancaonova.com\/paisecatequistas\/?p=12163"},"modified":"2021-07-15T14:07:56","modified_gmt":"2021-07-15T16:07:56","slug":"multiplicacao-dos-paes-2","status":"publish","type":"post","link":"https:\/\/blog.cancaonova.com\/paisecatequistas\/multiplicacao-dos-paes-2\/","title":{"rendered":"A multiplica\u00e7\u00e3o dos p\u00e3es"},"content":{"rendered":"<p>O Evangelho do 16\u00ba Domingo do Tempo Comum \u00e9 de S\u00e3o Marcos 6,30-34<\/p>\n<p>Naquele tempo,\u00a0os ap\u00f3stolos reuniram-se com Jesus e contaram tudo o que haviam feito e ensinado.<\/p>\n<p>Ele lhes disse: \u201cVinde sozinhos para um lugar deserto e descansai um pouco\u201d. Havia, de fato, tanta gente chegando e saindo que n\u00e3o tinham tempo nem para comer.<\/p>\n<p>Ent\u00e3o foram sozinhos, de barco, para um lugar deserto e afastado.\u00a0Muitos os viram partir e reconheceram que eram eles. Saindo de todas as cidades, correram a p\u00e9, e chegaram l\u00e1 antes deles.<\/p>\n<p>Ao desembarcar, Jesus viu uma numerosa multid\u00e3o e teve compaix\u00e3o, porque eram como ovelhas sem pastor. Come\u00e7ou, pois, a ensinar-lhes muitas coisas.<\/p>\n<p><a href=\"http:\/\/blog.cancaonova.com\/paisecatequistas\/files\/2021\/07\/multiplica\u00e7\u00e3o-dos-p\u00e3es.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-12164 alignnone\" src=\"http:\/\/blog.cancaonova.com\/paisecatequistas\/files\/2021\/07\/multiplica\u00e7\u00e3o-dos-p\u00e3es.jpg\" alt=\"\" width=\"901\" height=\"721\" srcset=\"https:\/\/blog.cancaonova.com\/paisecatequistas\/files\/2021\/07\/multiplica\u00e7\u00e3o-dos-p\u00e3es.jpg 2000w, https:\/\/blog.cancaonova.com\/paisecatequistas\/files\/2021\/07\/multiplica\u00e7\u00e3o-dos-p\u00e3es-300x240.jpg 300w, https:\/\/blog.cancaonova.com\/paisecatequistas\/files\/2021\/07\/multiplica\u00e7\u00e3o-dos-p\u00e3es-768x614.jpg 768w\" sizes=\"(max-width: 901px) 100vw, 901px\" \/><\/a><\/p>\n<p><a href=\"http:\/\/blog.cancaonova.com\/paisecatequistas\/files\/2021\/07\/multiplica\u00e7\u00e3o-dos-p\u00e3es-atividade.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-12165 alignnone\" src=\"http:\/\/blog.cancaonova.com\/paisecatequistas\/files\/2021\/07\/multiplica\u00e7\u00e3o-dos-p\u00e3es-atividade.jpg\" alt=\"\" width=\"951\" height=\"761\" srcset=\"https:\/\/blog.cancaonova.com\/paisecatequistas\/files\/2021\/07\/multiplica\u00e7\u00e3o-dos-p\u00e3es-atividade.jpg 2000w, https:\/\/blog.cancaonova.com\/paisecatequistas\/files\/2021\/07\/multiplica\u00e7\u00e3o-dos-p\u00e3es-atividade-300x240.jpg 300w, https:\/\/blog.cancaonova.com\/paisecatequistas\/files\/2021\/07\/multiplica\u00e7\u00e3o-dos-p\u00e3es-atividade-768x614.jpg 768w\" sizes=\"(max-width: 951px) 100vw, 951px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Evangelho do 16\u00ba Domingo do Tempo Comum \u00e9 de S\u00e3o Marcos 6,30-34 Naquele tempo,\u00a0os ap\u00f3stolos reuniram-se com Jesus e contaram tudo o que haviam feito e ensinado. Ele lhes disse: \u201cVinde sozinhos para um lugar deserto e descansai um&#8230;<\/p>\n","protected":false},"author":4340,"featured_media":12166,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/blog.cancaonova.com\/paisecatequistas\/wp-json\/wp\/v2\/posts\/12163"}],"collection":[{"href":"https:\/\/blog.cancaonova.com\/paisecatequistas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.cancaonova.com\/paisecatequistas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.cancaonova.com\/paisecatequistas\/wp-json\/wp\/v2\/users\/4340"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.cancaonova.com\/paisecatequistas\/wp-json\/wp\/v2\/comments?post=12163"}],"version-history":[{"count":2,"href":"https:\/\/blog.cancaonova.com\/paisecatequistas\/wp-json\/wp\/v2\/posts\/12163\/revisions"}],"predecessor-version":[{"id":12168,"href":"https:\/\/blog.cancaonova.com\/paisecatequistas\/wp-json\/wp\/v2\/posts\/12163\/revisions\/12168"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.cancaonova.com\/paisecatequistas\/wp-json\/wp\/v2\/media\/12166"}],"wp:attachment":[{"href":"https:\/\/blog.cancaonova.com\/paisecatequistas\/wp-json\/wp\/v2\/media?parent=12163"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.cancaonova.com\/paisecatequistas\/wp-json\/wp\/v2\/categories?post=12163"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.cancaonova.com\/paisecatequistas\/wp-json\/wp\/v2\/tags?post=12163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}