{"id":6560,"date":"2011-01-03T16:22:09","date_gmt":"2011-01-03T19:22:09","guid":{"rendered":"http:\/\/blog.cancaonova.com\/redacao\/?p=6560"},"modified":"2011-01-03T16:24:04","modified_gmt":"2011-01-03T19:24:04","slug":"2010-um-ano-de-crescimento-da-cancao-nova-na-internet","status":"publish","type":"post","link":"https:\/\/blog.cancaonova.com\/redacao\/2010-um-ano-de-crescimento-da-cancao-nova-na-internet\/","title":{"rendered":"2010, um ano de crescimento da Can\u00e7\u00e3o Nova na internet"},"content":{"rendered":"<p style=\"text-align: justify;\">Chegamos ao final de mais um ano, concluindo, dessa forma, as estat\u00edsticas do <a href=\"http:\/\/www.cancaonova.com\/\" target=\"_blank\">Portal Can\u00e7\u00e3o Nova<\/a>\u00a0referentes ao ano de 2010.<\/p>\n<p style=\"text-align: justify;\">O Portal Can\u00e7\u00e3o Nova, com 15 canais, no ano de 2010, teve um crescimento de 26% em rela\u00e7\u00e3o ao ano de 2009, fechando assim o ano com 98.328.402 acessos \u00fanicos em todas suas ferramentas.<\/p>\n<p style=\"text-align: justify;\">\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6565\" title=\"blog0011\" src=\"http:\/\/blog.cancaonova.com\/redacao\/files\/2011\/01\/blog0011.jpg\" alt=\"\" width=\"370\" height=\"250\" \/><\/p>\n<p style=\"text-align: justify;\">O site cat\u00f3lico lan\u00e7ou diversas ferramentas durante o ano de 2010, como a <a href=\"http:\/\/redebemtevi.com\/\" target=\"_blank\">Rede bem-te-vi<\/a>, o <a href=\"http:\/\/mapacatolico.com\/\" target=\"_blank\">Mapa Cat\u00f3lico<\/a>, <a href=\"http:\/\/www.portrasdaspalavras.com\/\" target=\"_blank\">Por tr\u00e1s das palavras<\/a>, entre outras. Essas foram algumas novidades que ajudaram a enriquecer esses dados durante o ano, como o lan\u00e7amento do novo <a href=\"http:\/\/radio.cancaonova.com\/\" target=\"_blank\">site da R\u00e1dio<\/a> em abril, respons\u00e1vel por um crescimento de 165,23% desse canal, com uma m\u00e9dia mensal de crescimento de 13,77%.<\/p>\n<p style=\"text-align: justify;\">Fazendo uso das diversas redes sociais, como o Twitter <a href=\"http:\/\/twitter.com\/cancaonova\" target=\"_blank\">@cancaonova<\/a> para a divulga\u00e7\u00e3o de ferramentas, cobertura de eventos, not\u00edcias do Brasil e do mundo, em 2010 o twitter @cancaonova ganhou + de 30 mil novos seguidores.<\/p>\n<p style=\"text-align: justify;\">Nossa rede social, o <a href=\"http:\/\/gentedefe.com\/\" target=\"_blank\">Gente de F\u00e9<\/a>, teve um crescimento de 129,17% durante o ano, tendo uma m\u00e9dia de crescimento mensal de 10,76% de acessos, atingindo a marca de 45.192 membros, 1.798 grupos e 22.381 blogs.<\/p>\n<p style=\"text-align: justify;\">Atingimos o n\u00famero m\u00e1ximo de 5 mil amigos permitido pelo servi\u00e7o do <a href=\"http:\/\/www.facebook.com\/cancaonova\" target=\"_blank\">Facebook<\/a>, tamb\u00e9m utilizamos o servi\u00e7o de p\u00e1ginas dessa rede social com mais de 1.813 f\u00e3s.<\/p>\n<p style=\"text-align: justify;\">No <a href=\"http:\/\/www.facebook.com\/cancaonova\" target=\"_blank\">Flickr<\/a>, nossa ferramenta de postagem de fotos, foram cadastradas mais de 25.034 mil fotos de todas as coberturas realizadas pela Can\u00e7\u00e3o Nova; apenas em dezembro de 2010 foram postadas 1.297 fotos.<\/p>\n<p style=\"text-align: justify;\">Encerramos o ano com 490 fotos enviadas ao Twitpic, servi\u00e7o de envio de fotos para o Twitter.<\/p>\n<p style=\"text-align: justify;\">Gustavo Borges<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chegamos ao final de mais um ano, concluindo, dessa forma, as estat\u00edsticas do Portal Can\u00e7\u00e3o Nova\u00a0referentes ao ano de 2010. O Portal Can\u00e7\u00e3o Nova, com 15 canais, no ano de 2010, teve um crescimento de 26% em rela\u00e7\u00e3o ao ano&#8230;<\/p>\n","protected":false},"author":1051,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1331],"tags":[6351,16379,641],"_links":{"self":[{"href":"https:\/\/blog.cancaonova.com\/redacao\/wp-json\/wp\/v2\/posts\/6560"}],"collection":[{"href":"https:\/\/blog.cancaonova.com\/redacao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.cancaonova.com\/redacao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.cancaonova.com\/redacao\/wp-json\/wp\/v2\/users\/1051"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.cancaonova.com\/redacao\/wp-json\/wp\/v2\/comments?post=6560"}],"version-history":[{"count":8,"href":"https:\/\/blog.cancaonova.com\/redacao\/wp-json\/wp\/v2\/posts\/6560\/revisions"}],"predecessor-version":[{"id":6570,"href":"https:\/\/blog.cancaonova.com\/redacao\/wp-json\/wp\/v2\/posts\/6560\/revisions\/6570"}],"wp:attachment":[{"href":"https:\/\/blog.cancaonova.com\/redacao\/wp-json\/wp\/v2\/media?parent=6560"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.cancaonova.com\/redacao\/wp-json\/wp\/v2\/categories?post=6560"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.cancaonova.com\/redacao\/wp-json\/wp\/v2\/tags?post=6560"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}